{"id":263,"count":1,"description":"","link":"https:\/\/hmcsviagens.pt\/index.php\/travel-keywords\/egito\/","name":"Egito","slug":"egito","taxonomy":"travel_keywords","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Arquivo de Egito - HMCS viagens<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hmcsviagens.pt\/index.php\/travel-keywords\/egito\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Arquivo de Egito - HMCS viagens\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hmcsviagens.pt\/index.php\/travel-keywords\/egito\/\" \/>\n<meta property=\"og:site_name\" content=\"HMCS viagens\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/hmcsviagens.pt\\\/index.php\\\/travel-keywords\\\/egito\\\/\",\"url\":\"https:\\\/\\\/hmcsviagens.pt\\\/index.php\\\/travel-keywords\\\/egito\\\/\",\"name\":\"Arquivo de Egito - HMCS viagens\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hmcsviagens.pt\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/hmcsviagens.pt\\\/index.php\\\/travel-keywords\\\/egito\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/hmcsviagens.pt\\\/index.php\\\/travel-keywords\\\/egito\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/hmcsviagens.pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Egito\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/hmcsviagens.pt\\\/#website\",\"url\":\"https:\\\/\\\/hmcsviagens.pt\\\/\",\"name\":\"HMCS viagens\",\"description\":\"Viagens de neg\u00f3cios, luas de mel, programas para escapadinhas, viagens \u00e0 medida, hot\u00e9is, hot\u00e9is de luxo, voos, transfers, excurs\u00f5es. Reserve na HMCS Viagens\",\"publisher\":{\"@id\":\"https:\\\/\\\/hmcsviagens.pt\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/hmcsviagens.pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/hmcsviagens.pt\\\/#organization\",\"name\":\"HMCS viagens\",\"url\":\"https:\\\/\\\/hmcsviagens.pt\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/hmcsviagens.pt\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/hmcsviagens.pt\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/logo-hmcs-viagens-quad-br-02-01.png\",\"contentUrl\":\"https:\\\/\\\/hmcsviagens.pt\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/logo-hmcs-viagens-quad-br-02-01.png\",\"width\":2250,\"height\":1210,\"caption\":\"HMCS viagens\"},\"image\":{\"@id\":\"https:\\\/\\\/hmcsviagens.pt\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/hmcsviagens\",\"https:\\\/\\\/www.instagram.com\\\/hmcsviagens\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/hmcsviagens\",\"https:\\\/\\\/www.pinterest.pt\\\/hmcsviagens\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCAvTyhGTW4S5VCpFgRM3YQw\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Arquivo de Egito - HMCS viagens","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hmcsviagens.pt\/index.php\/travel-keywords\/egito\/","og_locale":"pt_PT","og_type":"article","og_title":"Arquivo de Egito - HMCS viagens","og_url":"https:\/\/hmcsviagens.pt\/index.php\/travel-keywords\/egito\/","og_site_name":"HMCS viagens","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/hmcsviagens.pt\/index.php\/travel-keywords\/egito\/","url":"https:\/\/hmcsviagens.pt\/index.php\/travel-keywords\/egito\/","name":"Arquivo de Egito - HMCS viagens","isPartOf":{"@id":"https:\/\/hmcsviagens.pt\/#website"},"breadcrumb":{"@id":"https:\/\/hmcsviagens.pt\/index.php\/travel-keywords\/egito\/#breadcrumb"},"inLanguage":"pt-PT"},{"@type":"BreadcrumbList","@id":"https:\/\/hmcsviagens.pt\/index.php\/travel-keywords\/egito\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/hmcsviagens.pt\/"},{"@type":"ListItem","position":2,"name":"Egito"}]},{"@type":"WebSite","@id":"https:\/\/hmcsviagens.pt\/#website","url":"https:\/\/hmcsviagens.pt\/","name":"HMCS viagens","description":"Viagens de neg\u00f3cios, luas de mel, programas para escapadinhas, viagens \u00e0 medida, hot\u00e9is, hot\u00e9is de luxo, voos, transfers, excurs\u00f5es. Reserve na HMCS Viagens","publisher":{"@id":"https:\/\/hmcsviagens.pt\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hmcsviagens.pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/hmcsviagens.pt\/#organization","name":"HMCS viagens","url":"https:\/\/hmcsviagens.pt\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/hmcsviagens.pt\/#\/schema\/logo\/image\/","url":"https:\/\/hmcsviagens.pt\/wp-content\/uploads\/2021\/03\/logo-hmcs-viagens-quad-br-02-01.png","contentUrl":"https:\/\/hmcsviagens.pt\/wp-content\/uploads\/2021\/03\/logo-hmcs-viagens-quad-br-02-01.png","width":2250,"height":1210,"caption":"HMCS viagens"},"image":{"@id":"https:\/\/hmcsviagens.pt\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/hmcsviagens","https:\/\/www.instagram.com\/hmcsviagens","https:\/\/www.linkedin.com\/company\/hmcsviagens","https:\/\/www.pinterest.pt\/hmcsviagens","https:\/\/www.youtube.com\/channel\/UCAvTyhGTW4S5VCpFgRM3YQw"]}]}},"_links":{"self":[{"href":"https:\/\/hmcsviagens.pt\/index.php\/wp-json\/wp\/v2\/travel_keywords\/263","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hmcsviagens.pt\/index.php\/wp-json\/wp\/v2\/travel_keywords"}],"about":[{"href":"https:\/\/hmcsviagens.pt\/index.php\/wp-json\/wp\/v2\/taxonomies\/travel_keywords"}],"wp:post_type":[{"href":"https:\/\/hmcsviagens.pt\/index.php\/wp-json\/wp\/v2\/itineraries?travel_keywords=263"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}